{"id":12333,"date":"2018-11-07T09:20:57","date_gmt":"2018-11-07T08:20:57","guid":{"rendered":"https:\/\/www.viaprinto.de\/blog\/?p=12333"},"modified":"2023-05-19T12:44:28","modified_gmt":"2023-05-19T10:44:28","slug":"dateiformat_bitmap_pixel","status":"publish","type":"post","link":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/","title":{"rendered":"Dateiformate von Pixel- und Bitmap-Bildern"},"content":{"rendered":"<p>Daten sind jener digitale &#8222;Stoff&#8220;, den Designer, Produktioner oder Medienschaffende verwenden, um Gestaltung Wirklichkeit werden zu lassen. Die unterschiedlichen Datenformate haben jedoch Eigenschaften, die Vorteile und manchmal auch Nachteile f\u00fcr die Arbeit bringen. Wir stellen in den n\u00e4chsten drei Monaten in sechs Artikeln relevante Grafik-Datenformate f\u00fcr Designer vor. In der ersten Folge geht es um pixelbasierte Dateiformate. Was k\u00f6nnen sie und was unterscheidet gerade im Print-Bereich etwa Tiff, JPEG oder PNG voneinander?<\/p>\n<p>In diesem Artikel geht es um Grafik-Datenformate, die pixelbasiert sind, so genannte Rastergrafiken. Also nicht um Vektordaten wie sie in Adobe Illustrator erzeugt werden, die aufl\u00f6sungsunabh\u00e4ngig aus gef\u00fcllten Kurven und Linien bestehen. (\u00dcber Vektor-Formate informieren wir in Teil 3 unserer Serie). Das Besondere bei Pixelgrafiken ist, dass sie nicht ohne Qualit\u00e4tsverlust vergr\u00f6\u00dferbar sind. Will man ein Foto aus dem Web f\u00fcr den Offsetdruck nutzen, muss man auf die Aufl\u00f6sung achten: Bilder f\u00fcr den Offsetdruck m\u00fcssen mit 300 DPI aufgel\u00f6st sein, Bilder f\u00fcr das Web oft nur mit 72 DPI. W\u00fcrde man ein so aufgel\u00f6stes Bild im Offsetdruck drucken, erhielte man ein pixeliges Bild.<br \/>\nDateiformate f\u00fcr Farbfotos oder -Illustrationen, die von Medien-Designern f\u00fcr Drucksachen verwendet werden, sollten folgende Vorgaben unterst\u00fctzen:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>CMYK-Farbraum (nicht RGB wie im Web oder bei Fotokameras)<\/li>\n<li>Hohe Aufl\u00f6sung (300 DPI f\u00fcr Fotos)<\/li>\n<li>Hohe Farbtiefe (24 Bit, 32 Bit oder 48 Bit bieten Farbdifferenzierungs-Reserven gerade f\u00fcr die Bildbearbeitung und Bildmanipulation)<\/li>\n<li>Komprimierungen m\u00fcssen verlustfrei erfolgen<\/li>\n<\/ul>\n<p><strong>Der Wandel der Pixel-Dateiformate<\/strong><\/p>\n<p>Die Geschichte der zahlreichen Pixel-Datenformate erkl\u00e4rt sich aus immer neuen technischen Anforderungen. Das Tiff-Format etwa, das aus den Anf\u00e4ngen des computergest\u00fctzten Publizierens stammte, war nicht tauglich f\u00fcr das Internet. Das verlangte nach kleinen Dateiformaten, die im Web schnell geladen werden konnten. Der Einsatz von Pixelgrafiken im Web hat dazu gef\u00fchrt, dass vor allem die Komprimierungsm\u00f6glichkeiten ein wichtiges Thema wurden. Dies h\u00e4ngt mit den Faktoren Darstellungsqualit\u00e4t und Dateigr\u00f6\u00dfe im Verh\u00e4ltnis zur Komprimierungsart zusammen.<br \/>\nAber auch Patentstreitigkeiten bez\u00fcglich Datenformaten beschleunigten die Entwicklung neuer Datei-Formate: Das Datenformat PNG wurde als Reaktion auf das GIF-Patent entwickelt. Denn dessen Inhaber wollte Lizenzgeb\u00fchren f\u00fcr den Gebrauch des GIF-Formates. So wurde mit PNG ein kostenfreies Format entwickelt, das ohne Lizenzschwierigkeiten nutzbar war. JPG2000, ein Dateiformat mit besseren Komprimierungseigenschaften als sein Vorg\u00e4nger JPEG, konnte sich ebenfalls wegen anfallender Patentgeb\u00fchren nicht durchsetzen.<\/p>\n<p><strong>Dateiarten: Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme<\/strong><\/p>\n<p>Ein Mediengestalter muss sich mit unterschiedlichsten Dateiarten auskennen, gerade wenn Daten f\u00fcr die weitere Arbeit zugeliefert werde. Dazu z\u00e4hlen auch Texte und Schriften, deren Dateiformate aber nicht das Thema dieser Serie sind. Zusammengefasst ist ein Grafik-Designer mit folgenden Datei-Arten konfrontiert:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li><em>Pixel-Datenformate<\/em> wie TIFF, JPG oder PNG<\/li>\n<li><em>Vektor-Datenformate<\/em> wie CDR (Corel Draw), AI (Adobe Illustrator) und Acrobat (PDF)<\/li>\n<li><em>Produktions-Datenformat<\/em> PDF-X<\/li>\n<li><em>Font- Datenformate <\/em>bei den Schriften wie PostScript (PS), OpenType (OTF) oder TrueType (TT)<\/li>\n<li><em>Propriet\u00e4re (=herstellereigene) Programm-Datenformate<\/em> wie InDesign (INDD), Gimp (XCF) oder Photoshop (PSD)<\/li>\n<li><em>Officedatenformate<\/em> wie PowerPoint (PPT), Word (DOCX)<\/li>\n<li><em>Text-Datenformate<\/em> wie DOC, TXT, RTF oder ODT von OpenOffice<\/li>\n<\/ul>\n<p><strong>Vektorgrafiken als Gegenmodell zu den Pixel-Bildern<\/strong><\/p>\n<p>Das andere gro\u00dfe Bilddateimodell gegen\u00fcber den pixelorientierten Bildern sind Vektorgrafiken. Diese Illustrationen bestehen aus verlustfrei vergr\u00f6\u00dferbaren Konturen, die mit Farben oder Verl\u00e4ufen gef\u00fcllt werden. Die sogenannten Bezi\u00e9r-Kurven definieren Eckpunkte oder Kurvenverl\u00e4ufe mathematisch und bleiben immer glatt &#8211; ohne die Treppchenstruktur der Pixel-Grafiken.<\/p>\n<p><strong>Integration von Pixelgrafik und Vektorillustrationen<\/strong><\/p>\n<p>Waren diese beiden Datei-Welten \u201cPixel\u201d und \u201cVektor\u201d lange Zeit voneinander getrennt, geht die Tendenz hin zur Integration beider Formate. Adobe Photoshop als traditionelles Pixel-Grafik-Programm etwa kann Vektorgrafiken \u00f6ffnen und weiterbearbeiten. Das Vektorgrafikprogramm Adobe Illustrator kann schon seit l\u00e4ngerem Pixeldaten aufnehmen.<\/p>\n<p><strong>Wichtige Eigenschaften von Dateiformaten<\/strong><\/p>\n<p>F\u00fcr Medien-Designer, Reinzeichner und alle, die mit Bildern und visuellen Zeichen arbeiten, ist der Begriff \u201cDateiformat\u201d meist gleichbedeutend damit, wie sie Bilddateien wie Fotos oder Illustrationen abspeichern und einbinden. Dateiformate haben aber auch dar\u00fcber hinaus Relevanz und werden von Fragen begleitet wie:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li><em>Zuverl\u00e4ssigkeit:<\/em> Welches Datenformat bietet im Austausch mit Druckdienstleistern die h\u00f6chste Verl\u00e4sslichkeit?<\/li>\n<li><em>Kompatibilit\u00e4t:<\/em> Welche Programmdateien werden auf absehbare Zeit editierbar und damit f\u00fcr kommende Auflagen korrigierbar bleiben?<\/li>\n<li><em>Standardisierung:<\/em> Hier ist entscheidend, ob ein Datenformat dauerhaft mit mehreren Programmen plattform\u00fcbergreifend ge\u00f6ffnet werden kann.<\/li>\n<\/ul>\n<p><strong>Falsches Datenformat: Welche Fehler k\u00f6nnen auftreten?<\/strong><\/p>\n<p>Vor allem im Daten-Austausch zwischen Kunde und Dienstleistern ist das Wissen \u00fcber Datenformate erfolgs- und qualit\u00e4tsentscheidend. Tats\u00e4chlich sind \u201cfalsche\u201d Datenformate von Dateien neben dem unsachgem\u00e4ssen Einsatz und der Handhabung von Schriften und Farben die Hauptfehlerquelle bei der Drucksachen-Gestaltung. Aber was heisst \u201cfalsch\u201d? Was k\u00f6nnten die Folgen sein, wenn man nicht genau wei\u00df, welches Dateiformat welche Eigenschaften besitzt?<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>Zu kleiner Farbraum durch falschen Farbmodus einer Bilddatei. Ergebnis: Mangelnde Farbtreue des Bildes z.B. bei Kunstreproduktionen, Farbdetails werden unzureichend dargestellt oder fallen weg.<\/li>\n<li>Falsches Farbprofil mit dem Ergebnis von Abweichungen bei den Farben.<\/li>\n<li>Unzureichende Kompatibilit\u00e4t durch falsche Programmversion und damit z.B. zu alte Dateiversion. Ergebnis: Datei muss neu angelegt werden.<\/li>\n<li>Qualit\u00e4tsverlust bei Bildern durch vergr\u00f6ssern, hochrechnen oder zu starkes Komprimieren. Ergebnis: Die Sch\u00e4rfe, speziell die Konturensch\u00e4rfe, und Brillanz des Bildes sind unbefriedigend.<\/li>\n<li>Freisteller auf wei\u00dfem Hintergrund. Manche Datenformate enthalten Beschneidungspfade oder Transparenzen. W\u00e4re dies nicht der Fall, werden in einem Grafikprogramm freigestellte Bilder im Layoutprogramm mit einem wei\u00dfen eckigen Hintergrund angezeigt, wenn sie beispielsweise auf einem farbigen Hintergrund liegen.<\/li>\n<\/ul>\n<p><strong>Standard-Dateiformate f\u00fcr hohe Farbtiefen und h\u00f6chste Aufl\u00f6sungen<\/strong><\/p>\n<p>Gebr\u00e4uchliche Bildformate f\u00fcr den Druck und die Speicherung qualitativ hochwertiger Bilddatenbest\u00e4nde sind<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>Tiff,<\/li>\n<li>JPEG (unkomprimiert) und<\/li>\n<li>BMP.<\/li>\n<\/ul>\n<figure id=\"attachment_12366\" aria-describedby=\"caption-attachment-12366\" style=\"width: 705px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/Tiff_Komprimierung.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12366\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/Tiff_Komprimierung.png\" alt=\"\" width=\"705\" height=\"334\"><\/a><figcaption id=\"caption-attachment-12366\" class=\"wp-caption-text\">Oben: Bei den TIFF-Optionen sieht man links die aktivierte verlustfreie LZW-Komprimierung<\/figcaption><\/figure>\n<details>\n<summary><em><strong>TIFF\/TIF (Tagged Image File Format)<\/strong><\/em><\/summary>\n<p>TIFF ist der Standard vor allem in der Apple-Macintosh-Welt f\u00fcr unkomprimierte, hochaufgel\u00f6ste Bilder auch im Vierfarb-Druckstandard CMYK. Dieses Format ist eng verkn\u00fcpft mit der Geschichte des \u201cDesktop-Publishing\u201d. Das TIFF-Format ist allein aufgrund seiner Gr\u00f6\u00dfe nicht f\u00fcr den Einsatz auf Webseiten geeignet, vor allem aber ist es ein nicht gepuffertes Dateiformat. Ein Datenpuffer gleicht Unterschiede in der Geschwindigkeit von Datenverarbeitungsprozessen aus. Das hei\u00dft f\u00fcr Webseiten, dass Fotos zwischengespeichert und nachgeladen werden, wie das bei JPG oder PNG der Fall ist.<\/p>\n<p>Profil des Tiff-Formates:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>Verlustfreie Komprimierung, die gegen\u00fcber anderen Verfahren gro\u00dfe und qualitativ hochwertige Dateien erzeugt.<\/li>\n<li>Das Tiff-Format gilt als komplex und flexibel, es kann Farbseparationen und Alphakan\u00e4le enthalten oder in einer Datei verschieden gro\u00dfe Versionen eines Bildes.<\/li>\n<li>Tiffs sind mit allen g\u00e4ngigen Grafik-Programmen auf allen Betriebssystemen zu verarbeiten.<\/li>\n<\/ul>\n<\/details>\n<details>\n<summary><em><strong>BMP (Bitmap File Format)<\/strong><\/em><\/summary>\n<p>BMP ist gleichbedeutend mit DIB (Device Independent Bitmap) und gilt als Standard f\u00fcr hohe Bildqualit\u00e4t unter Windows. Was das TIFF-Format f\u00fcr die Apple-Macintosh-Welt ist, das ist f\u00fcr die Windows-Welt das BMP-Format. Beide Formate lassen sich plattform\u00fcbergreifend von allen wesentlichen Bildverarbeitungen \u00f6ffnen, bearbeiten und abspeichern.<\/p>\n<p>Profil des BMP-Formates:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>\u00c4hnlich wie das TIFF eignet sich das BMP nicht f\u00fcr das Internet, weil es eine Kompression unterst\u00fctzt, die verlustfrei ist und damit die Dateien nicht stark genug verkleinert.<\/li>\n<li>Unterst\u00fctzt werden im Farbfotobereich 8, 16, 24 oder 32 Bit Farbtiefe.<\/li>\n<li>Bei BMP sind Alphakan\u00e4le, Farbkorrektur sowie zus\u00e4tzlich angeh\u00e4ngte Informationen wie Metadaten anders als beim TIFF nicht enthalten.<\/li>\n<li>Der CMYK-Modus wird nicht unterst\u00fctzt.<\/li>\n<\/ul>\n<\/details>\n<figure id=\"attachment_12364\" aria-describedby=\"caption-attachment-12364\" style=\"width: 360px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/JPEG_Komprimierung.png\" data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12364 size-full\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/JPEG_Komprimierung.png\" alt=\"\" width=\"360\" height=\"317\"><\/a><figcaption id=\"caption-attachment-12364\" class=\"wp-caption-text\">Oben: Per Schieberegler l\u00e4sst sich im JPEG-Format der Komprimierungsgrad einstellen. &#8222;Progressiv&#8220; unter &#8222;Format-Optionen&#8220; erm\u00f6glicht den zun\u00e4chst niedrig aufgel\u00f6sten Bildaufbau auf Webseiten.<\/figcaption><\/figure>\n<details>\n<summary><em><strong>JPEG\/JPG (Joint Photographic Experts Group)<\/strong><\/em><\/summary>\n<p>Die Joint Photographic Experts Group ist ein Gremium, das 1992 Kompressionsverfahren definiert und dabei das JPEG-Format als Standard im Internet eingef\u00fchrt hat. Da JPEG auch in der Druckproduktion Verwendung findet, unterst\u00fctzt es neben dem RGB- auch den CMYK-Farbmodus. Das JPEG ist ein Datenformat, das Bilder auf Kosten der Qualit\u00e4t extrem komprimieren kann.<\/p>\n<p>Profil des JPEG-Formates<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>Zeitersparnis: Das JPEG-Format ist ein komprimiertes Format. Das hei\u00dft, dass ein JPEG selbst in maximaler Aufl\u00f6sung gegen\u00fcber einem unkomprimierten TIFF datenverlustbehaftet ist. Diese Unterschiede nimmt das menschliche Auge aber oft kaum wahr.<\/li>\n<li>Wiedergabe-Qualit\u00e4t: Deshalb eignet sich das JPG-Format in maximaler Aufl\u00f6sung auch f\u00fcr den Offsetdruck. Zu beachten ist aber, dass Fotos, die nicht in maximaler Aufl\u00f6sung im JPEG-Format zugeliefert werden, qualitativ unzureichend sein k\u00f6nnen. Es ist also darauf zu achten, dass das JPEG auf seinem Weg vom Fotografen bis zum Druck nicht komprimiert wird.<\/li>\n<li>Farbe: JPEG unterst\u00fctzt eine Farbtiefe von 24 oder 36 Bit. 24 Bit bildet maximal 16.777.216 unterschiedliche Farben ab und ist unter CMYK f\u00fcr den Offsetdruck geeignet.<\/li>\n<li>Komprimierung: Falsche das hei\u00dft zu starke Komprimierung kann Fotos f\u00fcr den Offsetdruck ungeeignet machen. JPGs bilden, je h\u00f6her sie komprimiert werden, sogenannten Artefakte. Das sind stufige Strukturen anstatt Bilddetails, die den Bildeindruck erheblich verschlechtern.<\/li>\n<\/ul>\n<\/details>\n<details>\n<summary><strong>PDF (Portable Document Format\/Photoshop PDF)<\/strong><\/summary>\n<p>Ein Format f\u00fcr das digitale Publizieren, nimmt eine Ausnahmestellung ein: Das mit Adobe Acrobat oder per Export aus einem Grafik-Programm erzeugte PDF-Format. Man findet PDFs niedrig aufgel\u00f6st sowohl auf Webseiten als auch hoch aufgel\u00f6st in Form von Belichtungsdateien im Offsetdruck. &#8222;Hoch&#8220; oder &#8222;niedrig&#8220; aufgel\u00f6st bezieht sich auf die Pixel-Bilddaten, die im PDF-Format enthalten sind. Man kann es sich als einen Daten-Container vorstellen, in dem Pixelbilder, Vektordaten und Schriften enthalten sein k\u00f6nnen, kurz, alle Gestaltungselemente, die zum Design geh\u00f6ren. Da PDF der Standard in der grafischen Industrie ist, k\u00f6nnen aus den meisten f\u00fcr Grafiker relevanten Programmen PDFs exportiert werden. \u00dcber Voreinstellungen kann man dabei die Fotoaufl\u00f6sung festlegen oder sie manuell \u00e4ndern. Das &#8222;X&#8220; im PDF-X-Format stellt sicher, dass Bilder im CMYK-Farbraum angelegt sind bzw. in diesen bei der PDF-Erstellung konvertiert werden und dass die Bildaufl\u00f6sungen f\u00fcr den Offsetdruck ausreichend sind. Sollte dies nicht der Fall sein, wird eine Warnmeldung ausgegeben. Mit dem Interpreter Ghostscript lassen sich PDF-Dateien unter Windows \u00f6ffnen und sogar korrigieren. Aus Photoshop heraus l\u00e4sst sich eine Pixelgrafik insgesamt als PDF-Datei abspeichern. Dabei sind bis zu 48 Bit Farbtiefe m\u00f6glich. Eine Besonderheit des PDF-Formates ist die unterst\u00fctzte Seitengr\u00f6\u00dfe:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>bis Version 3: 1,143 m \u00d7 1,143 m Seitengr\u00f6\u00dfe,<\/li>\n<li>bis Version 6: 5,08 m \u00d7 5,08 m Seitengr\u00f6\u00dfe und<\/li>\n<li>ab Version 7: 381 km \u00d7 381 km Seitengr\u00f6\u00dfe (Kein Satzfehler, Kilometer!)<\/li>\n<\/ul>\n<\/details>\n<p>(Mehr zum PDF-Format im dritten Teil unserer Serie zum Thema Vektordatenformate).<\/p>\n<p><strong>Targa und PNG<\/strong><br \/>\nZwei weitere verbreitete und verlustfrei komprimierbare Dateiformate spielen f\u00fcr Drucksachen keine Rolle, weil sie CMYK nicht unterst\u00fctzen.<\/p>\n<details>\n<summary><strong><em>TGA\/TARGA (= Truevision Advanced Raster Graphics Array)<\/em><\/strong><\/summary>\n<p>TARGA kann eingeschr\u00e4nkt Alphakan\u00e4le f\u00fcr Transparenzen und Gammakorrektur f\u00fcr die Bildverbesserung mit abspeichern, verf\u00fcgt \u00fcber 32 Bit Farbtiefe und erm\u00f6glicht eine verlustfreie Komprimierung. TARGA wird als Standard vor allem beim Bewegtbild etwa bei Spielen oder im Fernsehen eingesetzt.<\/p>\n<\/details>\n<details>\n<summary><strong><em>PNG (Portable Network Graphics)<\/em><\/strong><\/summary>\n<p>Gebr\u00e4uchlichstes unkomprimiertes Datenformat im Web mit den M\u00f6glichkeiten verlustfreier Kompression. Es verf\u00fcgt gegen\u00fcber dem Vorl\u00e4ufer GIF \u00fcber eine bessere Komprimierung und speichert je Einzelbild mehr Farben. Im Gegensatz zum GIF sind die Transparenz-Einstellungen umfassender.<\/p>\n<\/details>\n<p><strong>Weitere pixelorientierte Datenformate<\/strong><br \/>\nAdobe Photoshop unterst\u00fctzt eine Reihe von Pixeldatenformaten. Dabei handelt es sich im Wesentlichen um<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>spezialisierte Photoshop-Dateiformate,<\/li>\n<li>JPEG-Unterformate,<\/li>\n<li>weitere Web-Dateiformate f\u00fcr kleine Bildgr\u00f6\u00dfen und<\/li>\n<li>Spezialformate.<\/li>\n<\/ul>\n<p>Wo liegen die Einsatzfelder dieser Dateiformate, was sind ihre Unterschiede und welches ihre Vor- und Nachteile? (In Teil 4 unserer Serie zu Datenformaten stellen wir dar\u00fcber hinaus die propriet\u00e4ren Dateiformate von Programmen wie Photoshop, Gimp oder Adobe Illustrator vor.)<\/p>\n<figure id=\"attachment_12363\" aria-describedby=\"caption-attachment-12363\" style=\"width: 186px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/grafikdatenformate.png\" data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12363\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/grafikdatenformate.png\" alt=\"\" width=\"186\" height=\"397\"><\/a><figcaption id=\"caption-attachment-12363\" class=\"wp-caption-text\">Oben: Eine Liste der von Adobe Photoshop unterst\u00fctzten Datenformate.<\/figcaption><\/figure>\n<details>\n<summary><strong><em>Photoshop (PSD-Format)<\/em><\/strong><\/summary>\n<p>Adobe verf\u00fcgt mit dem PSD-Format \u00fcber ein programmeigenes Format, das Ebenen abspeichern kann und den vollen Photoshop-Funktions- und Darstellungsumfang unterst\u00fctzt. PSD-Dateien sind Arbeitsdateien von oft erheblicher Gr\u00f6\u00dfe. F\u00fcr die Endplatzierung von Bildern in anderen Grafikprogrammen werden die PSD-Dateien nach Fertigstellung auf eine Ebene reduziert.<\/p>\n<\/details>\n<details>\n<summary><em><strong>PSB (Photoshop Big\/Gro\u00dfes Dokumentenformat)<\/strong><\/em><\/summary>\n<p>PSB ist ein Photoshop-Sonderdateiformat f\u00fcr extreme Dateigr\u00f6\u00dfen. Die maximale Gr\u00f6\u00dfe von Fotodateien ob im PSD- oder TIFF-Format liegt bei 2 GB. PBS-Dateien k\u00f6nnen gr\u00f6\u00dfer sein und finden zum Beispiel Anwendung in der Satellitenfotografie oder bei bei 32-Bit-HDR-Bildern. Hierbei sind Seitenl\u00e4ngen bis zu 300.000 Pixeln m\u00f6glich. Eine Kompatibilit\u00e4t mit PSB ist ab Photoshop CS gegeben.<\/p>\n<\/details>\n<details>\n<summary><em><strong>Compuserve GIF (Graphics Interchange Format)<\/strong><\/em><\/summary>\n<p>Das GIF-Format ist ein Internetformat, das vom PNG-Format weitestgehend abgel\u00f6st wurde. Nur unterst\u00fctzt PNG keine Animationen, daf\u00fcr sind im GIF-Format keine Teil-Transparenzen enthalten, wie sie PNG bietet. Ein GIF ist auf 256 Farben beschr\u00e4nkt und unterst\u00fctzt eine Dateigr\u00f6\u00dfe mit Kantenl\u00e4ngen von bis zu 65.535 Pixeln.<\/p>\n<\/details>\n<details>\n<summary><em><strong>DICOM (Digital Imaging and Communications in Medicine)<\/strong><\/em><\/summary>\n<p>Ein Spezialformat f\u00fcr Bilder aus dem medizinischen Bereich, das die Bilddaten mit Patientendaten verkn\u00fcpft.<\/p>\n<\/details>\n<details>\n<summary><em><strong>Photoshop-EPS (Encapsulated PostScript)<\/strong><\/em><\/summary>\n<p>PostScript ist die Seitenbeschreibungssprache f\u00fcr Seitengestaltung, wie sie Grafikprogramme erzeugen. Wobei &#8222;encapsulated&#8220; &#8222;eingekapselt&#8220; hei\u00dft, weil die Postscriptdatei in einem transportablen Dateicontainer, dem EPS-File, enthalten ist. Heutzutage wird PostScript komfortabler in PDF-Dateien umgewandelt. Fr\u00fcher, als die verschiedenen Grafik-Programme noch nicht sehr kompatibel waren, war das sogenannte EPS-File (EPS oder EPSF) als Austausch-Dateiformat n\u00f6tig. Es kann von jedem wesentlichen Gestaltungsprogramm erzeugt werden, Pixelgrafik, Vektorgrafik und Schriften enthalten und seitenweise separiert belichtet werden. Das EPS-Format wurde durch PDF und das Adobe-Illustrator-Format &#8222;AI&#8220; abgel\u00f6st.<\/p>\n<\/details>\n<details>\n<summary><em><strong>IFF (Interchange File Format) <\/strong><\/em><\/summary>\n<p>Das IFF-Format ist nicht allein ein Bildformat sondern eignet sich dazu, verschiedenartige Dateien wie Musik, Bild, Film oder Text miteinander zu verbinden. Entwickelt wurde es vom Videospiel-Pionier Electronic Arts.<\/p>\n<\/details>\n<details>\n<summary><em><strong>JPEG 2000 (Joint Photographic Experts Group 2000)<\/strong><\/em><\/summary>\n<p>Der Nachfolger des JPEG war JPEG 2000. Der Ansatz des Formates war eine weiter verbesserte Kompressionsrate f\u00fcr kleinere Dateien, einhergehend mit der Beseitigung der JPEG-Artefakte bei zu starker Komprimierung. Dadurch wurde die Darstellungsqualit\u00e4t komprimierter Bilder verbessert. JPEG 2000 kann zudem gr\u00f6\u00dfere Bilder \u00fcber 64.000 Pixel Kantenl\u00e4nge verarbeiten, ist flexibler bei der Bildoptimierung und unterst\u00fctzt Alphakan\u00e4le f\u00fcr Transparenzen. Das Datenformat wird aber von vielen Bildverarbeitungsprogrammen nicht mehr unterst\u00fctzt.<\/p>\n<\/details>\n<details>\n<summary><em><strong>JPEG Stereo (Joint Photographic Experts Group Stereo)<\/strong><\/em><\/summary>\n<p>Das JPEG-Stereo-Format (als JPS-Datei) wird als Spezialformat f\u00fcr Mehrfachbilder f\u00fcr 3D-Effekte genutzt. Dabei werden zwei Bilder nebeneinander liegend in einer Datei platziert, eines f\u00fcr das linke Auge eines f\u00fcr das rechte. Zum Betrachten ist keine weitere Software n\u00f6tig. JPEG Stereo findet meist Anwendung als Speicherformat von 3D-Inhalten in Fotokameras.<\/p>\n<\/details>\n<details>\n<summary><strong><em>MPO\/MPF (Mehrbildformat auch Multi Picture Object oder Multi Picture Format)<\/em> <\/strong><\/summary>\n<p>Wie JPEG Stereo ist das Mehrbildformat f\u00fcr dreidimensional wirkende Fotos entwickelt worden. Das sind meist stereoskopische Bilder, die beim Betrachten r\u00e4umlich wirken. Allerdings haben MPO-Dateien den Nachteil, dass ohne spezielle Betrachtungssoftware immer nur ein Bild zu sehen ist und nicht beide gleichzeitig wie beim JPEG-Stereo-Format.<\/p>\n<\/details>\n<details>\n<summary><em><strong>PCX (Picture exchange)<\/strong><\/em><\/summary>\n<p>Das PCX-Format ist ein kaum noch unterst\u00fctztes Bilddatenformat, das f\u00fcr das Programm Paintbrush entwickelt wurde. Es unterst\u00fctzt bis zu 24 Bit Farbtiefe.<\/p>\n<\/details>\n<details>\n<summary><strong><em>RAW\/ PRAW (Photoshop Raw)<\/em><\/strong><\/summary>\n<p>Das Raw-Format ist ein unbearbeitetes Rohformat, das als digitales Negativ gilt. Raw-Bilder enthalten alle Bildinformationen, die die Kamera aufgezeichnet hat. Deshalb ist die Raw-Datei mehrfach so gro\u00df wie die JPEG-Datei. Mit Bildbearbeitungsprogrammen wie Photoshop, Gimp oder Lightroom werden Raws optimiert. Dabei sind die Tonwertergebnisse gerade bei Gegenlichtaufnahmen deutlich besser als automatisiert in der Kamera erzeugte JPEGs. Dabei gibt es nicht ein Raw-Format sondern zahlreiche. Denn jeder Kamerahersteller entwickelt sein eigenes. Die h\u00f6here Qualit\u00e4t des Raw liegt auch in der Farbtiefe begr\u00fcndet. W\u00e4hrend JPEGs bei 8 Bit 256 Helligkeitsstufen pro Kanal enthalten, liegt die tats\u00e4chlich aufgezeichnete Farbtiefe weit dar\u00fcber. Bei 10 Bit w\u00e4ren 1.024 Farbabstufungen vorhanden, bei 14 Bit bereits 16.384 Abstufungen pro Kanal. Das automatisierte JPEG w\u00fcrde hier also die Farbtiefe erheblich reduzieren. Bei der manuellen Bearbeitung kann es dann zu stufigen Farbabrissen komnmen, weil zu wenig Daten vorhanden sind.<\/p>\n<\/details>\n<details>\n<summary><em><strong>DNG (Digital Negative-Format)<\/strong> <\/em><\/summary>\n<p>Im Dschungel der unterschiedlichen Raw-Formate strebt Adobe mit dem Digital Negative-Format (DNG) eine Vereinheitlichung an. Das DNG ist das Raw-Format von Adobe. Unterst\u00fctzt werden CMYK- und RGB-Farbr\u00e4ume, ebenso Graustufenbilder inklusive Alphakan\u00e4len f\u00fcr Transparenzen sowie Bilder im Lab-Farbraum ohne Ebenen. Die Dateigr\u00f6\u00dfe ist nicht begrenzt.<\/p>\n<\/details>\n<details>\n<summary><em><strong>Pixar-Format <\/strong><\/em><\/summary>\n<p>Das Pixar-Bildformat kommt speziell f\u00fcr High-End-Grafik zum Beispiel bei 3D-Animationen zum Einsatz. Bearbeitet werden k\u00f6nnen RGB- oder Graustufenbilder mit Alphakanal.<\/p>\n<\/details>\n<details>\n<summary><em><strong>PBM (Portable Bit Map)<\/strong><\/em><\/summary>\n<p>Das plattformunabh\u00e4ngige Dateiformat Portable Bit Map ist f\u00fcr den Bildtransfer von 1-Bit-Grafiken zwischen Rechnersystemen geschaffen worden. Daf\u00fcr werden die Bilder im ASCII-Textformat gespeichert, das den maschinengesteuerten Bildtransfer beschleunigt. Das Bildformat kann zum Beispiel auf Handys inklusive Transparenzebene extrem schnell \u00fcbertragen werden. Die Formate PGM (Portable Graymap) f\u00fcr Graustufenbilder in 8 und 16 Bit und f\u00fcr Farbbilder PPM (Portable Pixmap) in 24 oder 48 Bit Farbtiefe erg\u00e4nzen und komplettieren das PBM-Dateiformat. PMB war das erste Dateiformat, das Datenmengen \u00fcber 2 GB pro Datei verarbeiten konnte.<\/p>\n<\/details>\n<details>\n<summary><em><strong>SCT (Scitex CT)<\/strong><\/em><\/summary>\n<p>Scitex-Workstations waren High-End in der grafischen Industrie f\u00fcr die sehr hochwertige Bildbearbeitung. Vom ScitexCT-Format unterst\u00fctzt werden CMYK, RGB und Graustufen allerdings ohne Transparenz-Alpha-Kanal. Die Dateien sind entsprechend der hohen Qualit\u00e4tsstandards sehr gro\u00df.<\/p>\n<\/details>\n<details>\n<summary><em><strong>Photoshop DCS 1 und DCS 2 (Desktop Colour Separation)<\/strong><\/em><\/summary>\n<p>In fr\u00fcheren Zeiten war es \u00fcblich, Vierfarbs\u00e4tze vorzuseparieren und in sogenannten DCS-Dateien abzuspeichern, um Farbausz\u00fcge f\u00fcr den Druck auszubelichten. DCS1 erm\u00f6glicht die CMYK-Separation, DCS2 ist f\u00fcr die Vollton-Sonderfarbenausgabe entwickelt worden. Das Photoshop-eigene PSD-Format hat inzwischen die Aufgaben von DCS weitestgehend \u00fcbernommen.<\/p>\n<\/details>\n<p><strong>Beispiel: Ein Druckprojekt mit vielen Fremddateien<\/strong><\/p>\n<p>Wer Drucksachen gestaltet, f\u00fcr die zahlreiche Firmenlogos von anderen Grafikern oder Agenturen zugeliefert werden, wei\u00df dass diese werden oft in den unterschiedlichen Datei-Formaten angeliefert werden. Aber wie geht man mit alten Dateiversionen um oder wie werden diese konvertiert? Was w\u00e4re also als Anforderung f\u00fcr die Anlieferung dieser Dateien wichtig? Wie etwa k\u00f6nnen aktuelle Photoshop-Dateien so abgespeichert werden, dass sie in \u00e4lteren Programmversionen problemlos zu \u00f6ffnen sind? F\u00fcr Pixeldaten gilt eine Angabe der Bildbearbeitungssoftware, mit der gearbeitet wird. Beispielsweise haben aktuelle Adobe-Photoshop-Versionen mitunter Probleme, \u00e4ltere TIFFs oder JPEGs zu \u00f6ffnen. Oder umgekehrt: Bilddaten, die in einer sehr neuen Programmversion abgespeichert wurden, lassen sich in der Regel in alten Programmversionen nicht mehr \u00f6ffnen. F\u00fcr die Anlieferung von Daten sollten deshalb folgende Anforderungen definiert werden, die der Zulieferer einhalten muss:<\/p>\n<ul style=\"margin-left: 50px;\">\n<li>Programm und Programmversion (dies kann vor allem dann wichtig sein, wenn man mit einer deutlich \u00e4lteren Programmversion als der aktuellen arbeitet)<\/li>\n<li>Betriebssystem (Windows, Mac, Linux).<\/li>\n<li>Dateiart (zum Beispiel Tiff, JPEG, PDF)<\/li>\n<li>Farbtiefe (in Bit, zum Beispiel 24 Bit oder 32-Bit)<\/li>\n<\/ul>\n<figure id=\"attachment_12365\" aria-describedby=\"caption-attachment-12365\" style=\"width: 1093px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/Photoshop_Kompatibilita\u0308t.png\" data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12365 size-full\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/Photoshop_Kompatibilita\u0308t.png\" alt=\"\" width=\"1093\" height=\"575\"><\/a><figcaption id=\"caption-attachment-12365\" class=\"wp-caption-text\">Oben: Damit sich kein Problem zwischen Programmversionen ergibt, sollten Bilder im Photoshop-Kompatibilit\u00e4tsmodus abgespeichert werden.<\/figcaption><\/figure>\n<p>Wenn man die Perspektive wechselt, also anschaut, welche Daten jemand an einen anderen liefert, stellt sich das Problem anders dar. Oft hat man &#8211; gerade als Laie &#8211; das Firmenlogo nur in einer Word- oder PowerPoint-Datei. Diese kann ggf. umgewandelt werden, um sie im Layoutprogramm belichtungsfertig zu platzieren.<\/p>\n<p><strong>Fazit: F\u00fcr Drucksachen bieten sich drei Datenformate an<\/strong><\/p>\n<p><strong>PDF-X:<\/strong> Professionell, mit vielen Einstellm\u00f6glichkeiten, in die man sich als Laie aber erst einarbeiten muss.<br \/>\n<strong>TIFF:<\/strong> Durch die verlustlose Komprimierung bietet das Format h\u00f6chste Foto-Qualit\u00e4t und Verl\u00e4sslichkeit.<br \/>\n<strong>JPEG:<\/strong> Schlankere Dateigr\u00f6\u00dfen und die Unterst\u00fctzung von CMYK machen JPEG f\u00fcr die gerade kleinformatigen Alltagsdrucksachen wie Flyer oder Faltbl\u00e4tter attraktiv.<\/p>\n<p style=\"text-align: center;\">F\u00fcr Sie zusammengefasst als Infografik:<br \/>\n<a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/viaprinto_infografik_pixeldatenformat.png\" data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><strong>Pixel-Dateiformate in der Bildverarbeitung<\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/viaprinto_infografik_pixeldatenformat.png\" data-rel=\"lightbox-image-5\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12376 size-full\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/viaprinto_infografik_pixeldatenformat.png\" alt=\"\" width=\"1419\" height=\"4906\"><\/a><\/p>\n<p>[av_button label=&#8217;PDF-Download der Infografik&#8216; link=&#8217;manually,https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/09\/viaprinto_infografik_pixeldatenformat.pdf&#8216; link_target=&#8217;_blank&#8216; size=&#8217;medium&#8216; position=&#8217;center&#8216; icon_select=&#8217;no&#8216; icon=&#8217;ue800&#8242; font=&#8217;entypo-fontello&#8216; color=&#8217;theme-color&#8216; custom_bg=&#8217;#444444&#8242; custom_font=&#8217;#ffffff&#8216;]<\/p>\n<figure id=\"attachment_8750\" aria-describedby=\"caption-attachment-8750\" style=\"width: 200px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2016\/04\/autor.jpg\" rel=\"attachment wp-att-8750\" data-rel=\"lightbox-image-6\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8750 size-medium\" src=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2016\/04\/autor-200x300.jpg\" alt=\"Ralf Wasselowski\" width=\"200\" height=\"300\"><\/a><figcaption id=\"caption-attachment-8750\" class=\"wp-caption-text\">Unser Gastautor: Ralf Wasselowski. Er betreibt die Agentur Conceptb\u00fcro in Essen und ist ein Kenner der Design-, Grafik- und Werbebranche. \u00a9Ralf Wasselowski<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Daten sind jener digitale &#8222;Stoff&#8220;, den Designer, Produktioner oder Medienschaffende verwenden, um Gestaltung Wirklichkeit werden zu lassen.<\/p>\n","protected":false},"author":8,"featured_media":12756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[3,5,21,367],"tags":[366],"class_list":["post-12333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-druck","category-layout","category-service","category-wissen","tag-datenformate"],"mb":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dateiformate von Pixel- &amp; Bitmap-Bildern | viaprinto<\/title>\n<meta name=\"description\" content=\"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dateiformate von Pixel- &amp; Bitmap-Bildern | viaprinto\" \/>\n<meta property=\"og:description\" content=\"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/\" \/>\n<meta property=\"og:site_name\" content=\"viaprinto Blog | Alles \u00fcber den Druck\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-07T08:20:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-19T10:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1690\" \/>\n\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah Sassenhagen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/\"},\"author\":{\"name\":\"Sarah Sassenhagen\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#\\\/schema\\\/person\\\/1aa19d31063bc939317c758ceb8b7c16\"},\"headline\":\"Dateiformate von Pixel- und Bitmap-Bildern\",\"datePublished\":\"2018-11-07T08:20:57+00:00\",\"dateModified\":\"2023-05-19T10:44:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/\"},\"wordCount\":3231,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg\",\"keywords\":[\"datenformate\"],\"articleSection\":[\"Druck\",\"Layout\",\"Service\",\"Wissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/\",\"name\":\"Dateiformate von Pixel- & Bitmap-Bildern | viaprinto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg\",\"description\":\"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg\",\"width\":1690,\"height\":642,\"caption\":\"Header Wissensreihe Datenformate Folge 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/dateiformat_bitmap_pixel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dateiformate von Pixel- und Bitmap-Bildern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/\",\"name\":\"viaprinto Blog | Alles \u00fcber den Druck\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#organization\",\"name\":\"viaprinto\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/viaprinto-blog-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/viaprinto-blog-logo.svg\",\"caption\":\"viaprinto\"},\"image\":{\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/viaprinto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/#\\\/schema\\\/person\\\/1aa19d31063bc939317c758ceb8b7c16\",\"name\":\"Sarah Sassenhagen\",\"url\":\"https:\\\/\\\/www.viaprinto.de\\\/blog\\\/author\\\/sarah-sassenhagenviaprinto-de\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dateiformate von Pixel- & Bitmap-Bildern | viaprinto","description":"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/","og_locale":"de_DE","og_type":"article","og_title":"Dateiformate von Pixel- & Bitmap-Bildern | viaprinto","og_description":"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog","og_url":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/","og_site_name":"viaprinto Blog | Alles \u00fcber den Druck","article_published_time":"2018-11-07T08:20:57+00:00","article_modified_time":"2023-05-19T10:44:28+00:00","og_image":[{"width":1690,"height":642,"url":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg","type":"image\/jpeg"}],"author":"Sarah Sassenhagen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#article","isPartOf":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/"},"author":{"name":"Sarah Sassenhagen","@id":"https:\/\/www.viaprinto.de\/blog\/#\/schema\/person\/1aa19d31063bc939317c758ceb8b7c16"},"headline":"Dateiformate von Pixel- und Bitmap-Bildern","datePublished":"2018-11-07T08:20:57+00:00","dateModified":"2023-05-19T10:44:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/"},"wordCount":3231,"commentCount":0,"publisher":{"@id":"https:\/\/www.viaprinto.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg","keywords":["datenformate"],"articleSection":["Druck","Layout","Service","Wissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/","url":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/","name":"Dateiformate von Pixel- & Bitmap-Bildern | viaprinto","isPartOf":{"@id":"https:\/\/www.viaprinto.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#primaryimage"},"image":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg","description":"\u00dcber Pixel, Vektoren, Druckdaten, Fonts, Texte und Programme. \u25b6 Datenformate bei der Mediengestaltung. | viaprinto Blog","breadcrumb":{"@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#primaryimage","url":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg","contentUrl":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2018\/11\/blogheader-wissensreihe-datenformate-1-1690x642px-@2x-1.jpg","width":1690,"height":642,"caption":"Header Wissensreihe Datenformate Folge 2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.viaprinto.de\/blog\/dateiformat_bitmap_pixel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.viaprinto.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Dateiformate von Pixel- und Bitmap-Bildern"}]},{"@type":"WebSite","@id":"https:\/\/www.viaprinto.de\/blog\/#website","url":"https:\/\/www.viaprinto.de\/blog\/","name":"viaprinto Blog | Alles \u00fcber den Druck","description":"","publisher":{"@id":"https:\/\/www.viaprinto.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.viaprinto.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.viaprinto.de\/blog\/#organization","name":"viaprinto","url":"https:\/\/www.viaprinto.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.viaprinto.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2022\/12\/viaprinto-blog-logo.svg","contentUrl":"https:\/\/www.viaprinto.de\/blog\/wp-content\/uploads\/2022\/12\/viaprinto-blog-logo.svg","caption":"viaprinto"},"image":{"@id":"https:\/\/www.viaprinto.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/viaprinto"]},{"@type":"Person","@id":"https:\/\/www.viaprinto.de\/blog\/#\/schema\/person\/1aa19d31063bc939317c758ceb8b7c16","name":"Sarah Sassenhagen","url":"https:\/\/www.viaprinto.de\/blog\/author\/sarah-sassenhagenviaprinto-de\/"}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/posts\/12333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/comments?post=12333"}],"version-history":[{"count":1,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/posts\/12333\/revisions"}],"predecessor-version":[{"id":17916,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/posts\/12333\/revisions\/17916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/media\/12756"}],"wp:attachment":[{"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/media?parent=12333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/categories?post=12333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.viaprinto.de\/blog\/wp-json\/wp\/v2\/tags?post=12333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}